{"id":8074,"count":2,"description":"","link":"https:\/\/www.ortizcamargo.com.br\/noticias\/tag\/advogado-isencao-imposto-de-renda-doenca-grave\/","name":"advogado isen\u00e7\u00e3o imposto de renda doen\u00e7a grave","slug":"advogado-isencao-imposto-de-renda-doenca-grave","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.ortizcamargo.com.br\/noticias\/wp-json\/wp\/v2\/tags\/8074"}],"collection":[{"href":"https:\/\/www.ortizcamargo.com.br\/noticias\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ortizcamargo.com.br\/noticias\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ortizcamargo.com.br\/noticias\/wp-json\/wp\/v2\/posts?tags=8074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}